{"id":213,"count":6,"description":"News von CORE Attorneys zum \u00f6ffentlichen Beschaffungsrecht in der Schweiz","link":"https:\/\/core-attorneys.com\/en\/news-insights\/category\/news-von-core-attorneys-zum-oeffentlichen-beschaffungsrecht\/","name":"Public Procurement","slug":"news-von-core-attorneys-zum-oeffentlichen-beschaffungsrecht","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/core-attorneys.com\/en\/wp-json\/wp\/v2\/categories\/213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/core-attorneys.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/core-attorneys.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/core-attorneys.com\/en\/wp-json\/wp\/v2\/posts?categories=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}